{"id":820,"count":1,"description":"","link":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/tag\/federal-student-loan-assistance-programs\/","name":"Federal Student Loan Assistance Programs","slug":"federal-student-loan-assistance-programs","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.8 (Yoast SEO v24.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Federal Student Loan Assistance Programs Archives - WooshPay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/tag\/federal-student-loan-assistance-programs\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Federal Student Loan Assistance Programs Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/tag\/federal-student-loan-assistance-programs\/\" \/>\n<meta property=\"og:site_name\" content=\"WooshPay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/tag\/federal-student-loan-assistance-programs\/\",\"url\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/tag\/federal-student-loan-assistance-programs\/\",\"name\":\"Federal Student Loan Assistance Programs Archives - WooshPay\",\"isPartOf\":{\"@id\":\"https:\/\/wooshpay.com\/fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/tag\/federal-student-loan-assistance-programs\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/tag\/federal-student-loan-assistance-programs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wooshpay.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Federal Student Loan Assistance Programs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wooshpay.com\/fr\/#website\",\"url\":\"https:\/\/wooshpay.com\/fr\/\",\"name\":\"WooshPay\",\"description\":\"One-stop payment platform\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wooshpay.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Federal Student Loan Assistance Programs Archives - WooshPay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/tag\/federal-student-loan-assistance-programs\/","og_locale":"pt_BR","og_type":"article","og_title":"Federal Student Loan Assistance Programs Archives","og_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/tag\/federal-student-loan-assistance-programs\/","og_site_name":"WooshPay","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/tag\/federal-student-loan-assistance-programs\/","url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/tag\/federal-student-loan-assistance-programs\/","name":"Federal Student Loan Assistance Programs Archives - WooshPay","isPartOf":{"@id":"https:\/\/wooshpay.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/tag\/federal-student-loan-assistance-programs\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/tag\/federal-student-loan-assistance-programs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wooshpay.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Federal Student Loan Assistance Programs"}]},{"@type":"WebSite","@id":"https:\/\/wooshpay.com\/fr\/#website","url":"https:\/\/wooshpay.com\/fr\/","name":"WooshPay","description":"Plataforma de pagamento em um s\u00f3 lugar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wooshpay.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/tags\/820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/posts?tags=820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}