{"id":11944,"date":"2023-08-05T08:38:51","date_gmt":"2023-08-05T08:38:51","guid":{"rendered":"https:\/\/wooshpay.com\/?post_type=docs&#038;p=11944"},"modified":"2023-08-09T07:32:21","modified_gmt":"2023-08-09T07:32:21","password":"","slug":"wooshpay-direct-api","status":"publish","type":"docs","link":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/docs\/wooshpay-direct-api\/","title":{"rendered":"WooshPay API direta"},"content":{"rendered":"<p><strong>Garantir a conformidade com o PCI para cart\u00e3o como m\u00e9todo de pagamento.<\/strong><\/p>\n\n\n\n<p>Qualquer pessoa envolvida com o processamento, a transmiss\u00e3o ou o armazenamento de dados de cart\u00f5es deve estar em conformidade com os Padr\u00f5es de Seguran\u00e7a de Dados do Setor de Cart\u00f5es de Pagamento (PCI DSS). A conformidade com o PCI \u00e9 uma responsabilidade compartilhada e se aplica tanto \u00e0 WooshPay quanto \u00e0 sua empresa. Ao aceitar pagamentos, voc\u00ea deve faz\u00ea-lo em conformidade com a PCI. A maneira mais simples de estar em conformidade com a PCI \u00e9 nunca ver (ou ter acesso a) os dados do cart\u00e3o.<\/p>\n\n\n\n<p>Use a API Payment Intents para criar uma integra\u00e7\u00e3o que possa lidar com fluxos de pagamento complexos. Ela rastreia um pagamento desde a cria\u00e7\u00e3o at\u00e9 o checkout e aciona etapas adicionais de autentica\u00e7\u00e3o quando necess\u00e1rio.<\/p>\n\n\n\n<p>Algumas das vantagens de usar a API Payment Intents incluem:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tratamento autom\u00e1tico de autentica\u00e7\u00e3o<\/li>\n\n\n\n<li>Sem cobran\u00e7as duplicadas<\/li>\n\n\n\n<li>Sem quest\u00f5es-chave de idempot\u00eancia<\/li>\n\n\n\n<li>Suporte para autentica\u00e7\u00e3o forte do cliente (SCA) e mudan\u00e7as regulat\u00f3rias semelhantes<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-complete-set-of-apis\">Um conjunto completo de APIs<\/h2>\n\n\n\n<p>Use a API Payment Intents juntamente com as APIs Setup Intents e Payment Methods. Essas APIs o ajudam a lidar com pagamentos din\u00e2micos (por exemplo, autentica\u00e7\u00e3o adicional como 3D Secure) e o preparam para a expans\u00e3o para outros pa\u00edses, permitindo que voc\u00ea ofere\u00e7a suporte a novas regulamenta\u00e7\u00f5es e m\u00e9todos de pagamento regionais.<\/p>\n\n\n\n<p>A cria\u00e7\u00e3o de uma integra\u00e7\u00e3o com a API de inten\u00e7\u00f5es de pagamento envolve duas a\u00e7\u00f5es: criar e confirmar uma PaymentIntent. No par\u00e1grafo a seguir, apresentaremos a API de inten\u00e7\u00e3o de pagamento por fluxo de pagamento:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Fluxo de pagamento n\u00e3o-3DS<\/li>\n\n\n\n<li>Fluxo de pagamento 3DS<\/li>\n<\/ol>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-non-3ds-payment-flow\">Fluxo de pagamento n\u00e3o-3DS<\/h3>\n\n\n\n<p>O fluxo de pagamento n\u00e3o 3D fornece um escopo claro da fun\u00e7\u00e3o do WooshPay em rela\u00e7\u00e3o a todo o processo de pagamento, desde o in\u00edcio do pagamento pelo cliente at\u00e9 sua finaliza\u00e7\u00e3o. O WooshPay usa um objeto PaymentIntent para representar sua inten\u00e7\u00e3o de cobrar o pagamento de um cliente, acompanhando as tentativas de cobran\u00e7a e as mudan\u00e7as no estado do pagamento durante todo o processo.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/kroki.io\/plantuml\/svg\/eNp9UrtuwzAM3P0V_AH_gIcgRYaiW9AOnVmZjgnoYYi0jfbrS9VJYRlFNUig7njkUTqLYtY5-Gaykx1PGBUus2gKlAEFHNSQZ7KjAFwBb5SXLUOq-_eUZJzw8wfRxpZrT447eE6gCQwJRXDCGxnE7Uk6odhDyr3JcRxSDqicYoNOeUElKyBG0w4umUp83TReotq-o2kj2hZBeCWdc4RI64Hc055ehbtWrzkt3BN8sPccb9CTInsBtD4Hjuj5ix5O7h5sHgY-3N0T_rKQ4sA5_O-hMJ9UKUz6W-borRKAlXW0ZNRZDh5ls1S1l0lmv6tqT1tcOKONaT3SqiHtAsuydTZh-0_fIgXUXA==\" alt=\"https:\/\/kroki.io\/plantuml\/svg\/eNp9UrtuwzAM3P0V_AH_gIcgRYaiW9AOnVmZjgnoYYi0jfbrS9VJYRlFNUig7njkUTqLYtY5-Gaykx1PGBUus2gKlAEFHNSQZ7KjAFwBb5SXLUOq-_eUZJzw8wfRxpZrT447eE6gCQwJRXDCGxnE7Uk6odhDyr3JcRxSDqicYoNOeUElKyBG0w4umUp83TReotq-o2kj2hZBeCWdc4RI64Hc055ehbtWrzkt3BN8sPccb9CTInsBtD4Hjuj5ix5O7h5sHgY-3N0T_rKQ4sA5_O-hMJ9UKUz6W-borRKAlXW0ZNRZDh5ls1S1l0lmv6tqT1tcOKONaT3SqiHtAsuydTZh-0_fIgXUXA==\"\/><\/figure>\n\n\n\n<p>Os m\u00e9todos de pagamento mostrados aos clientes durante o processo de checkout tamb\u00e9m s\u00e3o inclu\u00eddos no PaymentIntent. Voc\u00ea pode incluir todos os m\u00e9todos de pagamento que desejar, listando-os usando <code>dados_do_m\u00e9todo_de_pagamento<\/code> par\u00e2metro.<\/p>\n\n\n\n<p>O PaymentIntent cont\u00e9m um segredo do cliente, uma chave que \u00e9 exclusiva do PaymentIntent individual. Para usar o segredo do cliente, voc\u00ea deve obt\u00ea-lo do PaymentIntent em seu servidor e pass\u00e1-lo para o lado do cliente. Voc\u00ea pode usar diferentes abordagens para obter o segredo do cliente no lado do cliente.<\/p>\n\n\n\n<p><strong><em>Solicita\u00e7\u00e3o<\/em><\/strong> <a href=\"\/pt\/api-42631218\/\">Criar um PaymentIntent<\/a><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>{\n    \"amount\":1,\n    \"currency\": \"USD\",\n    \"confirm\":true,\n    \"payment_method_options\":{\n        \"card\":{\n            \"request_three_d_secure\": \"auto\"\n        }\n    },\n    \"payment_method_data\":{\n        \"type\": \"card\",\n        \"card\":{\n            \"cvc\": \"123\",\n            \"number\":\"4111111111111111\",\n            \"exp_month\": \"03\",\n            \"exp_year\": \"2027\"\n        }\n    },\n    \"merchant_order_id\":\"id1111\",\n    \"return_url\": \"https:\/\/wooshpay.com\"\n}<\/code><\/pre>\n\n\n\n<p><strong><em>Resposta<\/em><\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>{\n    \"id\":\"pi_1583366366029676544\",\n    \"object\": \"payment_intent\",\n    \"created\":1666338934000,\n    \"currency\": \"USD\",\n    \"amount\":1,\n    \"status\": \"succeeded\" (bem-sucedido),\n    \"description\":null,\n    \"metadata\":null,\n    \"livemode\":false,\n    \"merchant_order_id\":\"id1111\",\n    \"client_secret\":\"pi_1583366366029676544_secret_WKtUP8YmKmUKxcQPV0Zrmxym\",\n    \"last_payment_error\":null,\n    \"next_action\":\"\",\n    \"payment_method_types\":\"[\\\"card\\\",\\\"alipay\\\",\\\"wechat_pay\\\",\\\"alipayplus\\\",\\\"klarna\\\",\\\"ideal\\\",\\\"giropay\\\",\\\"sofort\\\",\\\"eps\\\",\\\"trustly\\\",\\\"bancontact\\\",\\\"p24\\\",\\\"sepa\\\"]\",\n    \"receipt_email\":null,\n    \"statement_descriptor\":null,\n    \"statement_descriptor_suffix\":null, \"statement_descriptor_suffix\":null,\n    \"cancel_at\":\"\",\n    \"cancellation_reason\":null,\n    \"confirmation_method\": \"automatic\",\n    \"payment_method_options\":\"{\\\"card\\\":{\\\"request_three_d_secure\\\":\\\"auto\\\",\\\"capture_method\\\":\\\"automatic\\\"}}\",\n    \"3ds_status\":nulo,\n    \"amount_capturable\":null\n}<\/code><\/pre>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3ds-payment-flow\">Fluxo de pagamento 3DS<\/h3>\n\n\n\n<p>Embora a Europa esteja introduzindo-a de forma desigual, voc\u00ea deve preparar seus fluxos de pagamento para estar pronto para a SCA o mais r\u00e1pido poss\u00edvel, se as regulamenta\u00e7\u00f5es da SCA afetarem voc\u00ea. A regulamenta\u00e7\u00e3o de autentica\u00e7\u00e3o forte do cliente na Europa exige o uso do 3DS para pagamentos com cart\u00e3o. O 3DS \u00e9 opcional em outras regi\u00f5es, mas voc\u00ea ainda pode us\u00e1-lo como uma ferramenta para reduzir fraudes.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/kroki.io\/plantuml\/svg\/eNrdlc1u2zAMx-9-Ct6yHdoHyKFokQLDgB26BsMuAQJWYmoCsuRKVIrs6Uf5I7W9dMC223KIY_FD5J8_KbdJMEpuXNXqkw236AU2OUloKAImMDA3OSZ9FAPPDFuKxz4izda_h5DqFk-dRSr9mKsbw2v4FEACqKUpCVt8JjXx1U1aJ_IWQrSajv0hxAaFg6_QCB9RSDdI6iZr2EQq7w99js9e9HviJlWSq5IQHkly9ODpdeFsaeo-e52U-hDDkS3BEzvH_hksCbJLgFrngT06_kFjJ0MP0DUxdjcEXGoh-APHZl4WvLLUYDDaC5FdVyX2ToSaVs4bj83eZan1nU0nG0R6yRzJXu_8IMOFvRQDyWnnYTW678uOwa-6Ji0d2RBYFAQTnKPOBh_u7zcfIUd3vRSyKv0V6ToZ1K14zeU9_1SQimbF-1G9depahNUajOw1aqUQQM3Wkgc-RGyol1i6TsNYz1hjIeaSWgtZ3pYXKvYy9sX0RRRMY6dcKQfQ2sLA4L_nXkV8m_awtDfdUdknMhoN3x6_wEumeFK30oRQTLDzUqPAKWQ9OW3rxpkZ9JATlZ2VOy36cAKtfjE5TCkY1jZtP8Ti0eZoakx0DfORwFnjjQuaearkGr52hb17NHRC1QjsJdep3FPEByA3NeqI_DP9CYsXSFQ8ccl2yq4X35w3KaSN-A1AzYyFJxwFmFE4CBSa1lFZGqPOwG3zU8MySVe9y9H_gtGCo3_EaHYDLO-MvyfsNxSlbAyRLfSEeIYq7UeVVcI62NWimAGf7fQS72H79d5awz2n1uFp6fles91xqm41t_7x_gTta7Cb\" alt=\"\"\/><\/figure>\n\n\n\n<p>Para o 3DS, normalmente, voc\u00ea direciona o cliente para uma p\u00e1gina de autentica\u00e7\u00e3o no site do banco e ele digita uma senha associada ao cart\u00e3o ou um c\u00f3digo enviado para o telefone.<\/p>\n\n\n\n<p><strong><em>Solicita\u00e7\u00e3o<\/em><\/strong> <a href=\"\/pt\/api-42631218\/\">Criar um PaymentIntent<\/a><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>{\n    \"amount\":1,\n    \"currency\": \"USD\",\n    \"confirm\":true,\n    \"payment_method_options\":{\n        \"card\":{\n            \"request_three_d_secure\": \"any\",\n            \"capture_method\": \"automatic\"\n        }\n    },\n    \"payment_method_data\":{\n        \"type\": \"card\",\n        \"card\":{\n            \"cvc\": \"123\",\n            \"number\":\"4111111111111111\",\n            \"exp_month\": \"03\",\n            \"exp_year\": \"2027\"\n        }\n    },\n    \"merchant_order_id\":\"id1111\",\n    \"return_url\": \"https:\/\/wooshpay.com\"\n}<\/code><\/pre>\n\n\n\n<p><strong><em>Resposta<\/em><\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>{\n    \"id\":\"pi_1583367070215569408\",\n    \"object\": \"payment_intent\",\n    \"created\":1666339102000,\n    \"currency\": \"USD\",\n    \"amount\":1,\n    \"status\": \"requires_action\",\n    \"description\":null,\n    \"metadata\":null,\n    \"livemode\":false,\n    \"merchant_order_id\":\"id1111\",\n    \"client_secret\":\"pi_1583367070215569408_secret_gXwuHGXjHgMqVw35oBInuYyC\",\n    \"last_payment_error\":null,\n    \"next_action\":\"{\\\"ddc_redirect\\\":{\\\"return_url\\\":\\\"https:\/\/wooshpay.com\\\",\\\"url\\\":\\\"https:\/\/jstest.wooshpay.com\/v1\/3ds\/index.html?c=2&amp;type=ddc&amp;dataId=pi_1583367070215569408&amp;token=eyJhbGciOiJIUzI1NiIsInR5cCI6IkpXVCJ9.eyJwYXlsb2FkIjp7InJlcXVlc3R0eXBlZGVzY3JpcHRpb25zIjpbIlRIUkVFRFFVRVJZIl0sImV4cGlyeWRhdGUiOiIwMy8yMDI3IiwiY3VycmVuY3lpc28zYSI6IlVTRCIsInNpdGVyZWZlcmVuY2UiOiJ0ZXN0X3N3b29zaHRyYW5zZmVybHRkOTczMjkiLCJiYXNlYW1vdW50IjoiMSIsInBhbiI6IjQxMTExMTExMTExMTExMTEiLCJzZWN1cml0eWNvZGUiOiIxMjMiLCJhY2NvdW50dHlwZWRlc2NyaXB0aW9uIjoiRUNPTSIsIm9yZGVycmVmZXJlbmNlIjoicGlfMTU4MzM2NzA3MDIxNTU2OTQwOCJ9LCJpc3MiOiJqd3RAc3dvb3NodHJhbnNmZXIuY29tIiwiaWF0IjoxNjY2MzM5MTAyfQ.L7CEYYRo95SesCt6WIsXr51MgHZKjkIDfmkooFTaUuo\\\"},\\\"type\\\":\\\"ddc_redirect\\\"}\",\n    \"payment_method_types\":\"[\\\"card\\\",\\\"alipay\\\",\\\"wechat_pay\\\",\\\"alipayplus\\\",\\\"klarna\\\",\\\"ideal\\\",\\\"giropay\\\",\\\"sofort\\\",\\\"eps\\\",\\\"trustly\\\",\\\"bancontact\\\",\\\"p24\\\",\\\"sepa\\\"]\",\n    \"receipt_email\":null,\n    \"statement_descriptor\":null,\n    \"statement_descriptor_suffix\":null, \"statement_descriptor_suffix\":null,\n    \"cancel_at\":\"\",\n    \"cancellation_reason\":null,\n    \"confirmation_method\": \"automatic\",\n    \"payment_method_options\":\"{\\\"card\\\":{\\\"request_three_d_secure\\\":\\\"any\\\",\\\"capture_method\\\":\\\"automatic\\\"}}\",\n    \"3ds_status\":nulo,\n    \"amount_capturable\":null\n}<\/code><\/pre>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-controlling-when-to-present-the-3d-secure-flow\">Controle de quando apresentar o fluxo do 3D Secure<\/h2>\n\n\n\n<p>O WooshPay aciona o 3DS automaticamente se for exigido por um requisito regulat\u00f3rio, como a autentica\u00e7\u00e3o forte do cliente. Quando voc\u00ea executa o 3D Secure, o WooshPay exige que seu cliente realize a autentica\u00e7\u00e3o para concluir o pagamento se a autentica\u00e7\u00e3o 3DS estiver dispon\u00edvel para um cart\u00e3o.<\/p>\n\n\n\n<p>Se um cart\u00e3o n\u00e3o for compat\u00edvel com o 3DS ou se ocorrer um erro durante o processo de autentica\u00e7\u00e3o, o pagamento continuar\u00e1 normalmente. Quando isso ocorre, a responsabilidade geralmente n\u00e3o \u00e9 transferida para o emissor, pois n\u00e3o houve uma autentica\u00e7\u00e3o 3DS bem-sucedida.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><code>autom\u00e1tico<\/code><br>O par\u00e2metro padr\u00e3o para 3DS \u00e9 <code>autom\u00e1tico<\/code>O controle de risco do WooshPay determinar\u00e1 se o 3DS deve ou n\u00e3o ser acionado. Para acionar o 3DS manualmente, defina <code>payment_method_options[card][request_three_d_secure]<\/code> para qualquer um ao criar ou confirmar um PaymentIntent ou SetupIntent.<\/li>\n\n\n\n<li><code>qualquer<\/code><br>Quando voc\u00ea define <code>request_three_d_secure<\/code> para <code>qualquer<\/code>O WooshPay exige que seu cliente realize a autentica\u00e7\u00e3o para concluir o pagamento com \u00eaxito se a autentica\u00e7\u00e3o 3DS estiver dispon\u00edvel para um cart\u00e3o. Se ela n\u00e3o estiver dispon\u00edvel para o cart\u00e3o em quest\u00e3o, o pagamento prossegue normalmente.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Ensure PCI compliance for card as payment method. Anyone involved with the processing, transmission, or storage of card data must comply with the Payment Card Industry Data Security Standards (PCI DSS). PCI compliance is a shared responsibility and applies to both WooshPay and your business. When accepting payments, you must do so in a PCI [&hellip;]<\/p>","protected":false},"author":6,"featured_media":11946,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[315],"doc_tag":[325,324,319],"class_list":["post-11944","docs","type-docs","status-publish","has-post-thumbnail","hentry","doc_category-online-payments","doc_tag-3d-secure","doc_tag-open-api","doc_tag-payment-flow"],"year_month":"2026-05","word_count":973,"total_views":"2281","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"zhaozixu","author_nicename":"zhaozixu","author_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/author\/zhaozixu\/"},"doc_category_info":[{"term_name":"Online Payments","term_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/docs-category\/online-payments\/"}],"doc_tag_info":[{"term_name":"3D secure","term_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/docs-tag\/3d-secure\/"},{"term_name":"open api","term_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/docs-tag\/open-api\/"},{"term_name":"Payment Flow","term_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/docs-tag\/payment-flow\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.8 (Yoast SEO v24.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>WooshPay Direct API - WooshPay<\/title>\n<meta name=\"description\" content=\"Use the Payment Intents API together with the Setup Intents and Payment Methods APIs. These APIs help you handle dynamic payments (for example, additional authentication like 3D Secure) and prepare you for expansion to other countries while allowing you to support new regulations and regional payment methods.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WooshPay Direct API\" \/>\n<meta property=\"og:description\" content=\"Use the Payment Intents API together with the Setup Intents and Payment Methods APIs. These APIs help you handle dynamic payments (for example, additional authentication like 3D Secure) and prepare you for expansion to other countries while allowing you to support new regulations and regional payment methods.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/\" \/>\n<meta property=\"og:site_name\" content=\"WooshPay\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-09T07:32:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1916\" \/>\n\t<meta property=\"og:image:height\" content=\"1044\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/\",\"url\":\"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/\",\"name\":\"WooshPay Direct API - WooshPay\",\"isPartOf\":{\"@id\":\"https:\/\/18.135.123.86\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow.png\",\"datePublished\":\"2023-08-05T08:38:51+00:00\",\"dateModified\":\"2023-08-09T07:32:21+00:00\",\"description\":\"Use the Payment Intents API together with the Setup Intents and Payment Methods APIs. These APIs help you handle dynamic payments (for example, additional authentication like 3D Secure) and prepare you for expansion to other countries while allowing you to support new regulations and regional payment methods.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/#primaryimage\",\"url\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow.png\",\"contentUrl\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow.png\",\"width\":1916,\"height\":1044,\"caption\":\"3ds flow\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/18.135.123.86\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/www.wooshpay.com\/it\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WooshPay Direct API\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/18.135.123.86\/es\/#website\",\"url\":\"https:\/\/18.135.123.86\/es\/\",\"name\":\"WooshPay\",\"description\":\"One-stop payment platform\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/18.135.123.86\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"WooshPay Direct API - WooshPay","description":"Use a API Payment Intents juntamente com as APIs Setup Intents e Payment Methods. Essas APIs o ajudam a lidar com pagamentos din\u00e2micos (por exemplo, autentica\u00e7\u00e3o adicional como 3D Secure) e o preparam para a expans\u00e3o para outros pa\u00edses, permitindo que voc\u00ea ofere\u00e7a suporte a novas regulamenta\u00e7\u00f5es e m\u00e9todos de pagamento regionais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/","og_locale":"pt_BR","og_type":"article","og_title":"WooshPay Direct API","og_description":"Use the Payment Intents API together with the Setup Intents and Payment Methods APIs. These APIs help you handle dynamic payments (for example, additional authentication like 3D Secure) and prepare you for expansion to other countries while allowing you to support new regulations and regional payment methods.","og_url":"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/","og_site_name":"WooshPay","article_modified_time":"2023-08-09T07:32:21+00:00","og_image":[{"width":1916,"height":1044,"url":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/","url":"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/","name":"WooshPay Direct API - WooshPay","isPartOf":{"@id":"https:\/\/18.135.123.86\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/#primaryimage"},"image":{"@id":"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/#primaryimage"},"thumbnailUrl":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow.png","datePublished":"2023-08-05T08:38:51+00:00","dateModified":"2023-08-09T07:32:21+00:00","description":"Use a API Payment Intents juntamente com as APIs Setup Intents e Payment Methods. Essas APIs o ajudam a lidar com pagamentos din\u00e2micos (por exemplo, autentica\u00e7\u00e3o adicional como 3D Secure) e o preparam para a expans\u00e3o para outros pa\u00edses, permitindo que voc\u00ea ofere\u00e7a suporte a novas regulamenta\u00e7\u00f5es e m\u00e9todos de pagamento regionais.","breadcrumb":{"@id":"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/#primaryimage","url":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow.png","contentUrl":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow.png","width":1916,"height":1044,"caption":"3ds flow"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wooshpay.com\/it\/docs\/wooshpay-direct-api\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/18.135.123.86\/es\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/www.wooshpay.com\/it\/docs\/"},{"@type":"ListItem","position":3,"name":"WooshPay Direct API"}]},{"@type":"WebSite","@id":"https:\/\/18.135.123.86\/es\/#website","url":"https:\/\/18.135.123.86\/es\/","name":"WooshPay","description":"Plataforma de pagamento em um s\u00f3 lugar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/18.135.123.86\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"uagb_featured_image_src":{"full":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow.png",1916,1044,false],"thumbnail":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow-150x150.png",150,150,true],"medium":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow-300x163.png",300,163,true],"medium_large":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow-768x418.png",768,418,true],"large":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow-1024x558.png",1024,558,true],"1536x1536":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow-1536x837.png",1536,837,true],"2048x2048":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow.png",1916,1044,false],"trp-custom-language-flag":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/3ds-flow-18x10.png",18,10,true]},"uagb_author_info":{"display_name":"zhaozixu","author_link":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/author\/zhaozixu\/"},"uagb_comment_info":0,"uagb_excerpt":"Ensure PCI compliance for card as payment method. Anyone involved with the processing, transmission, or storage of card data must comply with the Payment Card Industry Data Security Standards (PCI DSS). PCI compliance is a shared responsibility and applies to both WooshPay and your business. When accepting payments, you must do so in a PCI&hellip;","_links":{"self":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/docs\/11944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/comments?post=11944"}],"version-history":[{"count":0,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/docs\/11944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/media\/11946"}],"wp:attachment":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/media?parent=11944"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/doc_category?post=11944"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/pt\/wp-json\/wp\/v2\/doc_tag?post=11944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}