{"id":15405,"date":"2023-12-05T13:08:50","date_gmt":"2023-12-05T13:08:50","guid":{"rendered":"https:\/\/www.wooshpay.com\/?p=15405"},"modified":"2023-12-05T13:10:39","modified_gmt":"2023-12-05T13:10:39","slug":"the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one","status":"publish","type":"post","link":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/resources\/knowledge\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/","title":{"rendered":"Il fenomeno WeChat Pay: I portafogli digitali ridisegnano il panorama finanziario cinese (prima parte)"},"content":{"rendered":"<p class=\"wp-block-paragraph\">WeChat \u00e8 nato come semplice servizio di messaggistica nel 2011 e da allora \u00e8 diventato una parte essenziale della vita quotidiana in Cina. La sua estensione ai servizi finanziari con WeChat Pay ha cambiato notevolmente il modo di gestire le transazioni. Prima dell'avvento di WeChat Pay, il contante e i metodi bancari tradizionali dominavano le transazioni finanziarie in Cina. Questo articolo analizza il cambiamento significativo <a href=\"https:\/\/pay.weixin.qq.com\/index.php\/public\/wechatpay\">WeChat Pay<\/a> ha introdotto nelle attivit\u00e0 finanziarie cinesi.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-is-wechat-pay\">Che cos'\u00e8 WeChat Pay<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Incorporato nell'onnipresente app WeChat, WeChat Pay \u00e8 un servizio di portafoglio digitale che consente agli utenti di effettuare facilmente diverse transazioni. Tencent ha riferito che oltre un miliardo di utenti attivi ha abbracciato WeChat nel 2022, e molti utilizzano WeChat Pay per la sua comodit\u00e0 e sicurezza. La piattaforma impiega la tecnologia dei codici QR per un'esperienza di pagamento fluida tra utenti e commercianti e protegge le transazioni con una crittografia avanzata.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/523-1024x512.jpg?x-oss-process=style\/webp\" alt=\"Che cos&#039;\u00e8 WeChat Pay\" class=\"wp-image-15408\" srcset=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/523-1024x512.jpg?x-oss-process=style\/webp 1024w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/523-300x150.jpg?x-oss-process=style\/webp 300w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/523-768x384.jpg?x-oss-process=style\/webp 768w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/523-360x180.jpg?x-oss-process=style\/webp 360w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/523-1536x768.jpg?x-oss-process=style\/webp 1536w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/523-2048x1024.jpg?x-oss-process=style\/webp 2048w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/523-18x9.jpg?x-oss-process=style\/webp 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-the-pre-wechat-pay-scenario\">Lo scenario pre-WeChat Pay<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un tempo l'economia cinese si basava molto sulle transazioni in contanti. Le persone facevano acquisti, grandi e piccoli, usando la valuta fisica, mentre le carte di credito incontravano meno favore a causa di processi di richiesta macchinosi e di un'inclinazione culturale verso il contante.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-the-rise-of-mobile-payments-in-china\">L'ascesa dei pagamenti mobili in Cina<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un cambiamento cruciale si \u00e8 verificato con l'aumento dell'uso degli smartphone e un pi\u00f9 ampio accesso a Internet da parte della popolazione cinese. Le soluzioni di pagamento mobile hanno iniziato a guadagnare rapidamente popolarit\u00e0. I rapporti del 2016 mostrano che i servizi di pagamento mobile hanno conquistato oltre la met\u00e0 degli utenti di smartphone in Cina, con un netto aumento rispetto a pochi anni prima.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-how-wechat-pay-works\">Come funziona WeChat Pay<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Gli utenti collegano i loro conti bancari al portafoglio digitale dell'app per utilizzare WeChat Pay. Possono poi scannerizzare il biglietto di un commerciante <a href=\"https:\/\/en.wikipedia.org\/wiki\/QR_code\">Codice QR<\/a> o presentarne uno da scansionare per effettuare acquisti all'istante. Nel 2018, in occasione del Singles' Day, piattaforme mobili come WeChat Pay hanno elaborato milioni di transazioni, evidenziandone l'ampia adozione.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"524\" src=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/screen_shot_2017-11-03_at_133435_4lYK9vX-1024x524.png?x-oss-process=style\/webp\" alt=\"Come funziona WeChat Pay\" class=\"wp-image-15409\" srcset=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/screen_shot_2017-11-03_at_133435_4lYK9vX-1024x524.png?x-oss-process=style\/webp 1024w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/screen_shot_2017-11-03_at_133435_4lYK9vX-300x154.png?x-oss-process=style\/webp 300w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/screen_shot_2017-11-03_at_133435_4lYK9vX-768x393.png?x-oss-process=style\/webp 768w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/screen_shot_2017-11-03_at_133435_4lYK9vX-18x9.png?x-oss-process=style\/webp 18w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/screen_shot_2017-11-03_at_133435_4lYK9vX.png?x-oss-process=style\/webp 1078w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-impact-on-businesses-and-consumers\">Impatto su imprese e consumatori<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">WeChat Pay ha rivoluzionato il modo in cui le aziende ricevono i pagamenti, offrendo un'alternativa efficiente ai costosi sistemi dei punti vendita. \u00c8 stata una manna soprattutto per i piccoli venditori che ora possono accettare i pagamenti mostrando i loro codici QR.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"691\" src=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/\u5fae\u4fe1\u622a\u56fe_20231130205639-1024x691.jpg?x-oss-process=style\/webp\" alt=\"Impatto su imprese e consumatori\" class=\"wp-image-15410\" srcset=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/\u5fae\u4fe1\u622a\u56fe_20231130205639-1024x691.jpg?x-oss-process=style\/webp 1024w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/\u5fae\u4fe1\u622a\u56fe_20231130205639-300x202.jpg?x-oss-process=style\/webp 300w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/\u5fae\u4fe1\u622a\u56fe_20231130205639-768x518.jpg?x-oss-process=style\/webp 768w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/\u5fae\u4fe1\u622a\u56fe_20231130205639-360x243.jpg?x-oss-process=style\/webp 360w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/\u5fae\u4fe1\u622a\u56fe_20231130205639-1536x1037.jpg?x-oss-process=style\/webp 1536w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/\u5fae\u4fe1\u622a\u56fe_20231130205639-18x12.jpg?x-oss-process=style\/webp 18w, https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/12\/\u5fae\u4fe1\u622a\u56fe_20231130205639.jpg?x-oss-process=style\/webp 1809w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Per i consumatori, questa transizione ha semplificato notevolmente l'acquisto di beni e servizi. Basti pensare a Didi Chuxing, il principale servizio di ride-hailing cinese, che consente ai passeggeri di pagare con WeChat direttamente all'interno della sua app. Un altro esempio \u00e8 la partnership di Walmart con Tencent, che consente ai clienti dei suoi negozi in tutta la Cina di utilizzare WeChat Pay scansionando i codici QR alle casse: questa mossa snellisce il flusso dei clienti e riduce i tempi di attesa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusione<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In sintesi, WeChat Pay ha indubbiamente modificato le dinamiche monetarie in Cina, rendendo le transazioni facili ed efficienti sia per i consumatori che per le aziende. Con numerosi casi che evidenziano il suo vasto impatto sul commercio in tutto il Paese, \u00e8 evidente che i portafogli digitali stanno ponendo le basi per la futura innovazione finanziaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nei prossimi articoli continueremo ad approfondire l'argomento con nuovi spunti su come WeChat Pay sta influenzando il panorama economico globale.<\/p>","protected":false},"excerpt":{"rendered":"<p>WeChat \u00e8 nato come semplice servizio di messaggistica nel 2011 e da allora \u00e8 diventato una parte essenziale della vita quotidiana in Cina. La sua estensione ai servizi finanziari con WeChat Pay ha cambiato notevolmente il modo di gestire le transazioni. Prima dell'avvento di WeChat Pay, il contante e i metodi bancari tradizionali dominavano le transazioni finanziarie in Cina. Questo articolo approfondisce [...]<\/p>","protected":false},"author":1,"featured_media":15204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[22],"tags":[1231],"class_list":["post-15405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-online-payments","tag-qr-code-technology"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.8 (Yoast SEO v24.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The WeChat Pay Phenomenon: Digital Wallets Reshaping China&#039;s Financial Landscape(Part one) - WooshPay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wooshpay.com\/zh\/\u8d44\u6e90\/\u77e5\u8bc6\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The WeChat Pay Phenomenon: Digital Wallets Reshaping China&#039;s Financial Landscape(Part one)\" \/>\n<meta property=\"og:description\" content=\"WeChat began as a simple messaging service in 2011 and has since become an essential part of daily life in China. Its extension into financial services with WeChat Pay has notably changed how people handle transactions. Before the rise of WeChat Pay, cash and traditional banking methods dominated financial transactions in China. This article delves [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wooshpay.com\/zh\/\u8d44\u6e90\/\u77e5\u8bc6\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/\" \/>\n<meta property=\"og:site_name\" content=\"WooshPay\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-05T13:08:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-05T13:10:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"999\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"wooshpaysite\u7ba1\u7406\u5458\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"wooshpaysite\u7ba1\u7406\u5458\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/\",\"url\":\"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/\",\"name\":\"The WeChat Pay Phenomenon: Digital Wallets Reshaping China's Financial Landscape(Part one) - WooshPay\",\"isPartOf\":{\"@id\":\"https:\/\/wooshpay.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1.jpg\",\"datePublished\":\"2023-12-05T13:08:50+00:00\",\"dateModified\":\"2023-12-05T13:10:39+00:00\",\"author\":{\"@id\":\"https:\/\/wooshpay.com\/fr\/#\/schema\/person\/773f77ebc04c0b0c66979ecd0222fff2\"},\"breadcrumb\":{\"@id\":\"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/#primaryimage\",\"url\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1.jpg\",\"contentUrl\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1.jpg\",\"width\":999,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wooshpay.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The WeChat Pay Phenomenon: Digital Wallets Reshaping China&#8217;s Financial Landscape(Part one)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wooshpay.com\/fr\/#website\",\"url\":\"https:\/\/wooshpay.com\/fr\/\",\"name\":\"WooshPay\",\"description\":\"One-stop payment platform\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wooshpay.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/wooshpay.com\/fr\/#\/schema\/person\/773f77ebc04c0b0c66979ecd0222fff2\",\"name\":\"wooshpaysite\u7ba1\u7406\u5458\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/wooshpay.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2d785e60bef87c45b243b69db361f49ef08a251533ba24f30c0420fb92fca9f3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2d785e60bef87c45b243b69db361f49ef08a251533ba24f30c0420fb92fca9f3?s=96&d=mm&r=g\",\"caption\":\"wooshpaysite\u7ba1\u7406\u5458\"},\"sameAs\":[\"https:\/\/wooshpay.com\"],\"url\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/author\/wooshpaysiteadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il fenomeno WeChat Pay: I portafogli digitali stanno ridisegnando il panorama finanziario cinese (prima parte) - WooshPay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wooshpay.com\/zh\/\u8d44\u6e90\/\u77e5\u8bc6\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/","og_locale":"it_IT","og_type":"article","og_title":"The WeChat Pay Phenomenon: Digital Wallets Reshaping China's Financial Landscape(Part one)","og_description":"WeChat began as a simple messaging service in 2011 and has since become an essential part of daily life in China. Its extension into financial services with WeChat Pay has notably changed how people handle transactions. Before the rise of WeChat Pay, cash and traditional banking methods dominated financial transactions in China. This article delves [&hellip;]","og_url":"https:\/\/wooshpay.com\/zh\/\u8d44\u6e90\/\u77e5\u8bc6\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/","og_site_name":"WooshPay","article_published_time":"2023-12-05T13:08:50+00:00","article_modified_time":"2023-12-05T13:10:39+00:00","og_image":[{"width":999,"height":675,"url":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1.jpg","type":"image\/jpeg"}],"author":"wooshpaysite\u7ba1\u7406\u5458","twitter_card":"summary_large_image","twitter_misc":{"Written by":"wooshpaysite\u7ba1\u7406\u5458","Est. reading time":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/","url":"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/","name":"Il fenomeno WeChat Pay: I portafogli digitali stanno ridisegnando il panorama finanziario cinese (prima parte) - WooshPay","isPartOf":{"@id":"https:\/\/wooshpay.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/#primaryimage"},"image":{"@id":"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/#primaryimage"},"thumbnailUrl":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1.jpg","datePublished":"2023-12-05T13:08:50+00:00","dateModified":"2023-12-05T13:10:39+00:00","author":{"@id":"https:\/\/wooshpay.com\/fr\/#\/schema\/person\/773f77ebc04c0b0c66979ecd0222fff2"},"breadcrumb":{"@id":"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/#primaryimage","url":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1.jpg","contentUrl":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1.jpg","width":999,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/wooshpay.com\/zh\/%e8%b5%84%e6%ba%90\/%e7%9f%a5%e8%af%86\/online-payments\/2023\/12\/05\/the-wechat-pay-phenomenon-digital-wallets-reshaping-chinas-financial-landscapepart-one\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wooshpay.com\/fr\/"},{"@type":"ListItem","position":2,"name":"The WeChat Pay Phenomenon: Digital Wallets Reshaping China&#8217;s Financial Landscape(Part one)"}]},{"@type":"WebSite","@id":"https:\/\/wooshpay.com\/fr\/#website","url":"https:\/\/wooshpay.com\/fr\/","name":"WooshPay","description":"Piattaforma di pagamento unica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wooshpay.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/wooshpay.com\/fr\/#\/schema\/person\/773f77ebc04c0b0c66979ecd0222fff2","name":"wooshpaysite\u7ba1\u7406\u5458","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/wooshpay.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2d785e60bef87c45b243b69db361f49ef08a251533ba24f30c0420fb92fca9f3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d785e60bef87c45b243b69db361f49ef08a251533ba24f30c0420fb92fca9f3?s=96&d=mm&r=g","caption":"wooshpaysite\u7ba1\u7406\u5458"},"sameAs":["https:\/\/wooshpay.com"],"url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/author\/wooshpaysiteadmin\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1.jpg",999,675,false],"thumbnail":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1-150x150.jpg",150,150,true],"medium":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1-300x203.jpg",300,203,true],"medium_large":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1-768x519.jpg",768,519,true],"large":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1.jpg",999,675,false],"1536x1536":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1.jpg",999,675,false],"2048x2048":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1.jpg",999,675,false],"trp-custom-language-flag":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/11\/WeChat-Pay-02-999x675-1-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"wooshpaysite\u7ba1\u7406\u5458","author_link":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/author\/wooshpaysiteadmin\/"},"uagb_comment_info":12,"uagb_excerpt":"WeChat began as a simple messaging service in 2011 and has since become an essential part of daily life in China. Its extension into financial services with WeChat Pay has notably changed how people handle transactions. Before the rise of WeChat Pay, cash and traditional banking methods dominated financial transactions in China. This article delves&hellip;","_links":{"self":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/wp-json\/wp\/v2\/posts\/15405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/wp-json\/wp\/v2\/comments?post=15405"}],"version-history":[{"count":0,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/wp-json\/wp\/v2\/posts\/15405\/revisions"}],"wp:attachment":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/wp-json\/wp\/v2\/media?parent=15405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/wp-json\/wp\/v2\/categories?post=15405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/wp-json\/wp\/v2\/tags?post=15405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}