{"id":5218,"date":"2023-07-18T02:31:33","date_gmt":"2023-07-18T02:31:33","guid":{"rendered":"https:\/\/www.wooshpay.com\/?p=5218"},"modified":"2023-08-15T02:59:30","modified_gmt":"2023-08-15T02:59:30","slug":"school-bus-payment-portal","status":"publish","type":"post","link":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/resources\/knowledge\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/","title":{"rendered":"Lever le voile sur les myst\u00e8res de l'univers scolaire : bus, conseils d'administration et seaux d'argent"},"content":{"rendered":"<p><\/p>\n\n\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg?x-oss-process=style\/webp\" alt=\"School\u00a0bus\u00a0payment\u00a0portal\" width=\"450\" height=\"306\" \/><\/p>\n<p>Un portail de paiement pour les bus scolaires est une plateforme en ligne o\u00f9 les \u00e9l\u00e8ves et leurs familles peuvent payer pour les bus scolaires. <a href=\"https:\/\/www.wooshpay.com\/education-solution\/\">services de transport scolaire<\/a>. Il vous aide \u00e0 payer des choses telles que le transport vers et depuis l'\u00e9cole. L'\u00e9cole ou le district scolaire vous donne g\u00e9n\u00e9ralement acc\u00e8s \u00e0 ce portail par l'interm\u00e9diaire de son site web ou d'une page de connexion distincte.<\/p>\n<p>Lorsque vous utilisez un portail de paiement pour les bus scolaires, vous pouvez v\u00e9rifier le montant de votre dette et effectuer facilement des paiements. <a href=\"https:\/\/www.wooshpay.com\/\">paiements en ligne<\/a>. Vous pouvez utiliser une carte de cr\u00e9dit, une carte de d\u00e9bit ou un ch\u00e8que \u00e9lectronique pour payer. Certains portails vous permettent m\u00eame de mettre en place des paiements automatiques\uff0cvous pouvez consulter l'historique de vos paiements et recevoir des rappels lorsqu'il est temps de payer.<\/p>\n<p>Pour commencer \u00e0 utiliser un portail de paiement pour les autobus scolaires, vous devrez cr\u00e9er un compte et fournir quelques informations personnelles et financi\u00e8res. Il est important de lire les conditions g\u00e9n\u00e9rales du portail avant de les accepter. Et n'oubliez pas de toujours conserver vos informations de connexion et les d\u00e9tails de votre compte en toute s\u00e9curit\u00e9.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolboardpayment_01.jpg?x-oss-process=style\/webp\" alt=\"Paiement du conseil scolaire\" width=\"747\" height=\"508\" \/><\/p>\n<p>Un conseil scolaire est un groupe de fonctionnaires \u00e9lus ou nomm\u00e9s qui sont responsables de la gestion d'un district scolaire.<\/p>\n<p>Le conseil scolaire est charg\u00e9 de d\u00e9finir les politiques et de prendre les d\u00e9cisions qui affectent les \u00e9coles et les \u00e9l\u00e8ves du district. En termes de paiement\uff0c le conseil scolaire est charg\u00e9 d'\u00e9tablir le budget du district scolaire et de d\u00e9terminer comment les fonds seront utilis\u00e9s pour soutenir les \u00e9coles et les \u00e9l\u00e8ves du district.<\/p>\n<p>Il peut s'agir <a href=\"https:\/\/www.wooshpay.com\">payer les salaires des enseignants<\/a>Les frais de fonctionnement, d'entretien des b\u00e2timents, de mat\u00e9riel p\u00e9dagogique et d'autres d\u00e9penses.<\/p>\n<p>Le conseil scolaire peut \u00e9galement \u00eatre charg\u00e9 de g\u00e9rer les ressources financi\u00e8res du district et de veiller \u00e0 ce que les fonds du district soient utilis\u00e9s de mani\u00e8re efficace et efficiente. Si vous avez des questions sur le budget ou la gestion financi\u00e8re de votre district scolaire, vous devez contacter votre <a href=\"https:\/\/www.wooshpay.com\/education-solution\/\">conseil scolaire<\/a> ou le bureau financier du district pour plus d'informations.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolpaymentcalculator_01.jpg?x-oss-process=style\/webp\" alt=\"Calculatrice de frais de scolarit\u00e9\" width=\"770\" height=\"523\" \/><\/p>\n<p>Un calculateur de frais de scolarit\u00e9 est un outil pratique qui vous aide \u00e0 d\u00e9terminer le montant dont vous aurez besoin pour <a href=\"https:\/\/www.wooshpay.com\/education-solution\/\">d\u00e9penses universitaires<\/a>. Vous trouverez ces calculateurs sur les sites web des \u00e9tablissements d'enseignement. Il vous suffit d'entrer quelques informations vous concernant, comme le domaine que vous voulez \u00e9tudier, le nombre de cours que vous suivrez et le fait que vous soyez de la r\u00e9gion ou de l'ext\u00e9rieur. La calculatrice fait ensuite les calculs et vous donne une estimation de ce que vous aurez \u00e0 payer. <a href=\"https:\/\/www.wooshpay.com\/education-solution\/\">payer les frais de scolarit\u00e9 et les droits d'inscription<\/a> par an. Mais n'oublie pas que le montant r\u00e9el que tu devras d\u00e9bourser peut varier en fonction d'\u00e9l\u00e9ments tels que les aides financi\u00e8res, les bourses et les subventions. N'h\u00e9sitez donc pas \u00e0 vous adresser \u00e0 un conseiller financier de l'\u00e9cole pour avoir une id\u00e9e plus pr\u00e9cise de vos co\u00fbts !<\/p>","protected":false},"excerpt":{"rendered":"<p>Un portail de paiement pour les bus scolaires est une plateforme en ligne o\u00f9 les \u00e9l\u00e8ves et leurs familles peuvent payer pour les services de bus scolaires. Il vous aide \u00e0 payer des choses telles que le transport vers et depuis l'\u00e9cole. L'\u00e9cole ou le district scolaire vous donne g\u00e9n\u00e9ralement acc\u00e8s \u00e0 ce portail par le biais de son site web ou d'une page de connexion distincte. Lorsque [...]<\/p>","protected":false},"author":5,"featured_media":5219,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[23],"tags":[63,62,64,65],"class_list":["post-5218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education-payments","tag-online-platform","tag-school-bus-payment","tag-student-services","tag-transportation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.8 (Yoast SEO v24.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Unveiling the Mysteries of the School Universe:Buses,Board,and Buckets of Cash - WooshPay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/resources\/knowledge\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unveiling the Mysteries of the School Universe:Buses,Board,and Buckets of Cash\" \/>\n<meta property=\"og:description\" content=\"A school bus payment portal is like an online platform where students and their families can pay for the school bus services. It helps you pay for things like transportation to and from school. The school or school district usually gives you access to this portal through their website or a separate login page. When [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/resources\/knowledge\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/\" \/>\n<meta property=\"og:site_name\" content=\"WooshPay\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-18T02:31:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-15T02:59:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"412\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carmen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carmen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/\",\"url\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/\",\"name\":\"Unveiling the Mysteries of the School Universe:Buses,Board,and Buckets of Cash - WooshPay\",\"isPartOf\":{\"@id\":\"https:\/\/www.wooshpay.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg\",\"datePublished\":\"2023-07-18T02:31:33+00:00\",\"dateModified\":\"2023-08-15T02:59:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.wooshpay.com\/#\/schema\/person\/d1e8b50ce9401cf26ad4e063a38c11e4\"},\"breadcrumb\":{\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/#primaryimage\",\"url\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg\",\"contentUrl\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg\",\"width\":412,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wooshpay.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unveiling the Mysteries of the School Universe:Buses,Board,and Buckets of Cash\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wooshpay.com\/#website\",\"url\":\"https:\/\/www.wooshpay.com\/\",\"name\":\"WooshPay\",\"description\":\"One-stop payment platform\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wooshpay.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.wooshpay.com\/#\/schema\/person\/d1e8b50ce9401cf26ad4e063a38c11e4\",\"name\":\"Carmen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.wooshpay.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d0676f347bf6bab0695a958a8c355902b8deb007e7a59cf3a4cb0837da902583?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d0676f347bf6bab0695a958a8c355902b8deb007e7a59cf3a4cb0837da902583?s=96&d=mm&r=g\",\"caption\":\"Carmen\"},\"url\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/author\/alyssa\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Unveiling the Mysteries of the School Universe:Buses,Board,and Buckets of Cash - WooshPay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/resources\/knowledge\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/","og_locale":"fr_FR","og_type":"article","og_title":"Unveiling the Mysteries of the School Universe:Buses,Board,and Buckets of Cash","og_description":"A school bus payment portal is like an online platform where students and their families can pay for the school bus services. It helps you pay for things like transportation to and from school. The school or school district usually gives you access to this portal through their website or a separate login page. When [&hellip;]","og_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/resources\/knowledge\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/","og_site_name":"WooshPay","article_published_time":"2023-07-18T02:31:33+00:00","article_modified_time":"2023-08-15T02:59:30+00:00","og_image":[{"width":412,"height":280,"url":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg","type":"image\/jpeg"}],"author":"Carmen","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Carmen","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/","url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/","name":"Unveiling the Mysteries of the School Universe:Buses,Board,and Buckets of Cash - WooshPay","isPartOf":{"@id":"https:\/\/www.wooshpay.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/#primaryimage"},"image":{"@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/#primaryimage"},"thumbnailUrl":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg","datePublished":"2023-07-18T02:31:33+00:00","dateModified":"2023-08-15T02:59:30+00:00","author":{"@id":"https:\/\/www.wooshpay.com\/#\/schema\/person\/d1e8b50ce9401cf26ad4e063a38c11e4"},"breadcrumb":{"@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/#primaryimage","url":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg","contentUrl":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg","width":412,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/ja\/resources\/%e7%9f%a5%e8%ad%98\/education-payments\/2023\/07\/18\/school-bus-payment-portal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wooshpay.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Unveiling the Mysteries of the School Universe:Buses,Board,and Buckets of Cash"}]},{"@type":"WebSite","@id":"https:\/\/www.wooshpay.com\/#website","url":"https:\/\/www.wooshpay.com\/","name":"WooshPay","description":"Plate-forme de paiement unique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wooshpay.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.wooshpay.com\/#\/schema\/person\/d1e8b50ce9401cf26ad4e063a38c11e4","name":"Carmen","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wooshpay.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d0676f347bf6bab0695a958a8c355902b8deb007e7a59cf3a4cb0837da902583?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0676f347bf6bab0695a958a8c355902b8deb007e7a59cf3a4cb0837da902583?s=96&d=mm&r=g","caption":"Carmen"},"url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/author\/alyssa\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg",412,280,false],"thumbnail":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01-150x150.jpg",150,150,true],"medium":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01-300x204.jpg",300,204,true],"medium_large":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg",412,280,false],"large":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg",412,280,false],"1536x1536":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg",412,280,false],"2048x2048":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01.jpg",412,280,false],"trp-custom-language-flag":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/schoolbuspaymentportal_01-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"Carmen","author_link":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/author\/alyssa\/"},"uagb_comment_info":0,"uagb_excerpt":"A school bus payment portal is like an online platform where students and their families can pay for the school bus services. It helps you pay for things like transportation to and from school. The school or school district usually gives you access to this portal through their website or a separate login page. When\u2026","_links":{"self":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/wp-json\/wp\/v2\/posts\/5218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/wp-json\/wp\/v2\/comments?post=5218"}],"version-history":[{"count":0,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/wp-json\/wp\/v2\/posts\/5218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/wp-json\/wp\/v2\/media\/5219"}],"wp:attachment":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/wp-json\/wp\/v2\/media?parent=5218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/wp-json\/wp\/v2\/categories?post=5218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/fr\/wp-json\/wp\/v2\/tags?post=5218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}