{"id":518,"count":1,"description":"Etiqueta de Apple Pay","link":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/tag\/apple-pay\/","name":"Apple Pay","slug":"apple-pay","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.8 (Yoast SEO v24.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Apple Pay Archives - WooshPay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/tag\/apple-pay\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apple Pay Archives\" \/>\n<meta property=\"og:description\" content=\"Tag of Apple Pay\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/tag\/apple-pay\/\" \/>\n<meta property=\"og:site_name\" content=\"WooshPay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/tag\/apple-pay\/\",\"url\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/tag\/apple-pay\/\",\"name\":\"Apple Pay Archives - WooshPay\",\"isPartOf\":{\"@id\":\"https:\/\/18.135.123.86\/es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/tag\/apple-pay\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/tag\/apple-pay\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/18.135.123.86\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apple Pay\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/18.135.123.86\/es\/#website\",\"url\":\"https:\/\/18.135.123.86\/es\/\",\"name\":\"WooshPay\",\"description\":\"One-stop payment platform\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/18.135.123.86\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Apple Pay Archives - WooshPay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/tag\/apple-pay\/","og_locale":"es_ES","og_type":"article","og_title":"Apple Pay Archives","og_description":"Tag of Apple Pay","og_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/tag\/apple-pay\/","og_site_name":"WooshPay","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/tag\/apple-pay\/","url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/tag\/apple-pay\/","name":"Archivos de Apple Pay - WooshPay","isPartOf":{"@id":"https:\/\/18.135.123.86\/es\/#website"},"breadcrumb":{"@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/tag\/apple-pay\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/it\/tag\/apple-pay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/18.135.123.86\/es\/"},{"@type":"ListItem","position":2,"name":"Apple Pay"}]},{"@type":"WebSite","@id":"https:\/\/18.135.123.86\/es\/#website","url":"https:\/\/18.135.123.86\/es\/","name":"WooshPay","description":"Plataforma de pago \u00fanica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/18.135.123.86\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/tags\/518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/posts?tags=518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}