{"id":11956,"date":"2023-08-05T08:58:26","date_gmt":"2023-08-05T08:58:26","guid":{"rendered":"https:\/\/wooshpay.com\/?post_type=docs&#038;p=11956"},"modified":"2023-08-05T08:58:27","modified_gmt":"2023-08-05T08:58:27","password":"","slug":"payouts","status":"publish","type":"docs","link":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/","title":{"rendered":"Pagos"},"content":{"rendered":"<p>Wooshpay es capaz de hacer pagos a su cuenta bancaria. Puede ver una lista de todos sus pagos en su cuenta bancaria en el panel de control. Tambi\u00e9n, puede recuperar la lista de pagos por API.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-payout-status\">Estado del pago<\/h2>\n\n\n\n<p>Hay cinco estados de una solicitud de pago. Una vez creado el pago, el estado inicial ser\u00e1 pendiente. Cuando se llama a la API de cancelaci\u00f3n, el estado ser\u00e1 cancelado, lo que conlleva la cancelaci\u00f3n del proceso de pago. Cuando la solicitud se env\u00eda al banco, el estado pasa a in_transit. Entonces se descompone en dos posibilidades: si el procesamiento bancario falla, conducir\u00e1 a Failed del resultado del pago; si el procesamiento bancario tiene \u00e9xito, entonces conducir\u00e1 al estado paid.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/api.apifox.cn\/api\/v1\/projects\/1296482\/resources\/385616\/image-preview\" alt=\"Estado del pago\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-payout-speed\">Velocidad de pago<\/h2>\n\n\n\n<p>Mientras que el calendario de pagos se refiere a la cadencia con la que se abonan sus fondos (por ejemplo, el d\u00eda de la semana), la velocidad de pago se refiere al tiempo que tardan sus fondos en estar disponibles. La velocidad de pago var\u00eda seg\u00fan el pa\u00eds y suele expresarse como T+X d\u00edas. Algunos procesadores de pagos pueden comenzar \"T\" a partir de su hora de liquidaci\u00f3n interna, es decir, cuando los fondos aterrizan en sus cuentas bancarias.<\/p>\n\n\n\n<p>\"T\" se refiere a la hora de la transacci\u00f3n, es decir, la hora de la confirmaci\u00f3n o captura inicial del pago. Por ejemplo, si su cuenta est\u00e1 radicada en un pa\u00eds con una velocidad de pago est\u00e1ndar T+3 y est\u00e1 en un programa de pago manual, su saldo estar\u00e1 disponible para el pago en un plazo de 3 d\u00edas laborables desde el momento en que captur\u00f3 un pago.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-minimum-payout-amount\">Importe m\u00ednimo de pago<\/h2>\n\n\n\n<p>El importe m\u00ednimo de pago suele ser una unidad b\u00e1sica de la moneda local. Por ejemplo, en Estados Unidos, el pago m\u00ednimo es de un d\u00f3lar estadounidense, mientras que en Singapur es de un d\u00f3lar de Singapur.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-payout-speed-and-minimum-amount\">Velocidad de pago e importe m\u00ednimo<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th><strong>Pa\u00eds\/Regi\u00f3n<\/strong><\/th><th><strong>Velocidad de pago<\/strong><strong>(D\u00edas laborables)<\/strong><\/th><th><strong>Importe m\u00ednimo<\/strong><strong>(Moneda local)<\/strong><\/th><th><strong>Importe m\u00e1ximo<\/strong><strong>(Moneda local)<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Hong Kong<\/td><td>1-3<\/td><td>0,01 HKD<\/td><td>\/<\/td><\/tr><tr><td>Jap\u00f3n<\/td><td>1-3<\/td><td>100,00 JPY<\/td><td>\/<\/td><\/tr><tr><td>Corea del Sur<\/td><td>1-3<\/td><td>1,00 KRW<\/td><td>\/<\/td><\/tr><tr><td>Uni\u00f3n Europea (Zona \u00danica de Pagos en Euros)<\/td><td>1-3<\/td><td>0,01 EUR<\/td><td>\/<\/td><\/tr><tr><td>Reino Unido<\/td><td>1-3<\/td><td>0,01 EUR<\/td><td>\/<\/td><\/tr><tr><td>Estados Unidos de Am\u00e9rica<\/td><td>1-3<\/td><td>0,01 USD<\/td><td>\/<\/td><\/tr><tr><td>Nueva Zelanda<\/td><td>1-3<\/td><td>0,01 NZD<\/td><td>\/<\/td><\/tr><tr><td>Australia<\/td><td>1-3<\/td><td>0,01 AUD<\/td><td>\/<\/td><\/tr><tr><td>Malasia<\/td><td>1-3<\/td><td>1,00 MYR<\/td><td>\/<\/td><\/tr><tr><td>Singapur<\/td><td>1-3<\/td><td>0,01 SGD<\/td><td>\/<\/td><\/tr><tr><td>Corea del Sur<\/td><td>1-3<\/td><td>1 KRW<\/td><td>\/<\/td><\/tr><tr><td>Tailandia<\/td><td>1-3<\/td><td>10 THB<\/td><td>500000 THB<\/td><\/tr><tr><td>Vietnam<\/td><td>1-3<\/td><td>10000 VND<\/td><td>300000000 VND<\/td><\/tr><tr><td>Filipinas<\/td><td>1-3<\/td><td>10 PHP<\/td><td>500000 PHP<\/td><\/tr><tr><td>Indonesia<\/td><td>1-3<\/td><td>10000 IDR<\/td><td>1000000000 IDR<\/td><\/tr><tr><td>China continental<\/td><td>1-3<\/td><td>300 CNY<\/td><td>\/<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>La tabla anterior es un caso est\u00e1ndar. La velocidad de pago puede variar debido a los diferentes bancos, y puede tardar unos d\u00edas m\u00e1s. El tipo de negocio y el pa\u00eds en el que te encuentres tambi\u00e9n pueden afectar a la velocidad de pago.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-start-your-payout\">Iniciar el pago<\/h2>\n\n\n\n<p>Puedes crear un pago con la API de Wooshpay. En general, hay dos escenarios para los pagos\uff1a.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Pagos globales<\/li>\n\n\n\n<li>Pagos a China<\/li>\n<\/ol>\n\n\n\n<p>Antes de crear un pago, es necesario especificar algunos par\u00e1metros:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><code>beneficiario<\/code> : Los datos del beneficiario deben indicarse en este objeto, si se trata de un pago inicial que <code>beneficiario_id<\/code> no se utiliza. ) .<\/li>\n\n\n\n<li><code>tipo<\/code> : El tipo debe ser <code>empresa<\/code> (para empresa) o <code>beneficiario<\/code> (para particulares)<\/li>\n\n\n\n<li><code>empresa<\/code> : Se requieren los datos de la empresa, incluyendo <code>nombre_registrado_de_la_empresa<\/code>, <code>direcci\u00f3n<\/code> y <code>informaci\u00f3n_adicional<\/code>.<\/li>\n\n\n\n<li><code>beneficiario<\/code> : Se requieren los datos de la empresa, incluyendo <code>direcci\u00f3n<\/code>, <code>informaci\u00f3n_adicional<\/code>.<\/li>\n\n\n\n<li><code>destino<\/code> : Requiere la informaci\u00f3n de la cuenta bancaria o tarjeta a la que se envi\u00f3 el pago.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-global-payouts\">Pagos globales<\/h3>\n\n\n\n<p>Crear un pago global<\/p>\n\n\n\n<p>Para crear un nuevo Pago Global proporcionando directamente la informaci\u00f3n del beneficiario<\/p>\n\n\n\n<p><strong><em>A petici\u00f3n de la empresa<\/em><\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>{\n  \"datos_beneficiario\": {\n    \"tipo\": \"business\",\n    \"business\": {\n      \"company_registered_name\": \"XXX ltd\",\n      \"address\": {\n        \"l\u00ednea1\": \"Bloque 3A\",\n        \"line2\": \"Parque XX\",\n        \"c\u00f3digo_postal\": \"98109\",\n        \"city\": \"Seattle\",\n        \"state\": \"WA\",\n        \"country\": \"USA\"\n      },\n      \"additional_info\": {\n        \"business_registration_number\": \"32342353535334234MCA4\",\n        \"legal_rep_first_name\": \"Ming\",\n        \"legal_rep_last_name\": \"Zhang\",\n        \"legal_rep_id_type\": \"NATIONAL_ID\",\n        \"legal_rep_id_number\": \"233923874838920238X\",\n        \"legal_rep_email\": \"xxx@email.com\",\n        \"legal_rep_phone\": \"13727282938\"\n      }\n    }\n  },\n  \"amount\": 666,\n  \"currency\": \"cny\",\n  \"description\": \"Puedes a\u00f1adir la descripci\u00f3n aqu\u00ed\",\n  \"tipo\": \"cuenta_bancaria\",\n  \"datos_destino\": {\n    \"fuente\": {\n      \"nombre_titular_cuenta\": \"xxxx ltd\",\n      \"account_holder_type\": \"company\",\n      \"bank_name\": \"Bank of America\",\n      \"country\": \"USA\",\n      \"currency\": \"USD\",\n      \"account_number\": \"6210000000000002\"\n    }\n  }\n}<\/code><\/pre>\n\n\n\n<p><strong><em>Respuesta<\/em><\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>  {\n      \"id\": \"po_1654453881670729728\",\n      \"objeto\": \"pago\",\n      \"creado\": 1683287519000,\n      \"moneda\": \"CNY\",\n      \"importe\": 666,\n      \"descripci\u00f3n\": \"Puedes a\u00f1adir la descripci\u00f3n aqu\u00ed\",\n      \"estado\": \"pendiente\",\n      \"destino\": {\n          \"id\": \"ba_1654453883419754496\",\n          \"objeto\": \"cuenta_bancaria\",\n          \"creada\": 1683287519000,\n          \"pa\u00eds\": \"USA\",\n          \"moneda\": \"USD\",\n          \"huella digital\": \"817902e3b6a2cf61eebc484f89467be650063413\",\n          \"last4\": \"0002\",\n          \"account_holder_name\": \"xxxx ltd\",\n          \"account_holder_type\": \"company\"\n      },\n      \"livemode\": falso,\n      \"type\": \"bank_account\",\n      \"method\": \"standard\",\n      \"beneficiario\": {\n          \"id\": \"bf_1654453881691701248\",\n          \"objeto\": \"beneficiario\",\n          \"tipo\": \"business\",\n          \"negocio\": {\n              \"direcci\u00f3n\": {\n                  \"ciudad\": \"Seattle\",\n                  \"country\": \"USA\",\n                  \"l\u00ednea1\": \"Bloque 3A\",\n                  \"line2\": \"Parque XX\",\n                  \"state\": \"WA\",\n                  \"c\u00f3digo_postal\": \"98109\"\n              },\n              \"company_registered_name\": \"XXX ltd\",\n              \"additional_info\": {\n                  \"business_registration_number\": \"32342353535334234MCA4\",\n                  \"legal_rep_first_name\": \"Ming\",\n                  \"legal_rep_last_name\": \"Zhang\",\n                  \"legal_rep_id_type\": \"NATIONAL_ID\",\n                  \"legal_rep_id_number\": \"233923874838920238X\",\n                  \"legal_rep_email\": \"xxx@email.com\",\n                  \"legal_rep_phone\": \"13727282938\"\n              }\n          }\n      }\n  }<\/code><\/pre>\n\n\n\n<p><strong><em>Solicitud individual<\/em><\/strong><br>Para crear un pago facilitando directamente los datos del beneficiario<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>  {\n    \"datos_beneficiario\": {\n      \"tipo\": \"beneficiario\",\n      \"beneficiario\":{\n          \"direcci\u00f3n\": {\n          \"l\u00ednea1\": \"### Ave\",\n          \"line2\": \"#501\",\n          \"c\u00f3digo_postal\": \"98109\",\n          \"city\": \"Seattle\",\n          \"state\": \"WA\",\n          \"country\": \"USA\"\n        },\n      \"additional_info\": {\n          \"last_name\": \"Kale\",\n          \"first_name\": \"Leo\",\n          \"id_type\": \"NATIONAL_ID\",\n          \"id_country_iso_code\": \"USA\",\n          \"id_number\":\"234242423423434X\",\n          \"email\": \"xxx@email.com\",\n          \"phone\": \"1234534343\"\n        }\n      }\n    },\n    \"importe\": 1000,\n    \"moneda\": \"USD\",\n    \"description\": \"Puedes a\u00f1adir la descripci\u00f3n aqu\u00ed\",\n    \"tipo\": \"cuenta_bancaria\",\n    \"datos_destino\": {\n      \"fuente\": {\n        \"nombre_titular_cuenta\": \"Leo Kale\",\n        \"account_holder_type\": \"individual\",\n        \"bank_name\": \"Bank of America\",\n        \"country\": \"USA\",\n        \"currency\": \"USD\",\n        \"account_number\": \"6210000000000002\"\n      }\n    }\n  }<\/code><\/pre>\n\n\n\n<p><strong><em>Respuesta<\/em><\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>  {\n      \"id\": \"po_1654455721024028672\",\n      \"object\": \"pago\",\n      \"creado\": 1683287958000,\n      \"moneda\": \"USD\",\n      \"importe\": 1000,\n      \"descripci\u00f3n\": \"Puedes a\u00f1adir la descripci\u00f3n aqu\u00ed\",\n      \"estado\": \"pendiente\",\n      \"destino\": {\n          \"id\": \"ba_1654455722777247744\",\n          \"objeto\": \"cuenta_bancaria\",\n          \"creada\": 1683287957000,\n          \"pa\u00eds\": \"USA\",\n          \"moneda\": \"USD\",\n          \"huella digital\": \"3e27cccbe614f34d9b688b9eed46cea1cf9eee1d\",\n          \"last4\": \"0002\",\n          \"account_holder_name\": \"Leo Kale\",\n          \"account_holder_type\": \"individual\"\n      },\n      \"livemode\": falso,\n      \"type\": \"bank_account\",\n      \"method\": \"standard\",\n      \"beneficiario\": {\n          \"id\": \"bf_1654455721040805888\",\n          \"objeto\": \"beneficiario\",\n          \"tipo\": \"beneficiario\",\n          \"beneficiario\": {\n              \"direcci\u00f3n\": {\n                  \"ciudad\": \"Seattle\",\n                  \"country\": \"USA\",\n                  \"line1\": \"### Ave\",\n                  \"line2\": \"#501\",\n                  \"state\": \"WA\",\n                  \"c\u00f3digo_postal\": \"98109\"\n              },\n              \"additional_info\": {\n                  \"email\": \"xxx@email.com\",\n                  \"phone\": \"1234534343\",\n                  \"nombre\": \"LeoKale\",\n                  \"apellido\": \"Kale\",\n                  \"first_name\": \"Leo\",\n                  \"id_type\": \"NATIONAL_ID\",\n                  \"id_country_iso_code\": \"USA\",\n                  \"id_number\": \"234242423423434X\"\n              }\n          }\n      }\n  }<\/code><\/pre>\n\n\n\n<p>Pagos peri\u00f3dicos<\/p>\n\n\n\n<p>Si ya ha pagado alguna vez al beneficiario, podr\u00eda crear un pago utilizando <code>beneficiario_id<\/code>, <code>destination_id<\/code> que se guarda en el servidor y que puedes encontrar en la \u00faltima respuesta.<\/p>\n\n\n\n<p>En el caso anterior, <code>beneficiario_id<\/code> es <code>\"bf_1579357548861980672\"<\/code> y <code>destination_id<\/code> es <code>\"ba_1654455722777247744\"<\/code><\/p>\n\n\n\n<p><strong><em>Solicitar<\/em><\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>{\n  \"beneficiario\": \"bf_1579357548861980672\",\n  \"importe\": 888,\n  \"moneda\": \"USD\",\n  \"descripci\u00f3n\": \"Puedes a\u00f1adir la descripci\u00f3n aqu\u00ed\",\n  \"tipo\": \"cuenta_bancaria\",\n  \"destino\": \"ba_1654455722777247744\"\n}<\/code><\/pre>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-payouts-to-china\">Pagos a China<\/h3>\n\n\n\n<p>Crear un nuevo pago a China<\/p>\n\n\n\n<p>La diferencia con los pagos globales es que tiene que enviar el <code>payment_intents_id<\/code> al solicitar un pago a China.<\/p>\n\n\n\n<p><strong><em>Solicitar<\/em><\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>  {\n    \"beneficiario\": \"bf_1579357548861980672\",\n    \"importe\": 666,\n    \"moneda\": \"cny\",\n    \"descripci\u00f3n\": \"Puedes a\u00f1adir la descripci\u00f3n aqu\u00ed\",\n    \"tipo\": \"cuenta_bancaria\",\n    \"datos_destino\": {\n      \"fuente\": {\n        \"nombre_titular_cuenta\": \"xxxx ltd\",\n        \"account_holder_type\": \"company\",\n        \"bank_name\": \"Bank of China\",\n        \"country\": \"CN\",\n        \"moneda\": \"CNY\",\n        \"n\u00famero_de_cuenta\": \"6210000000000002\"\n      }\n    },\n    \"payment_intents_id\": [\n      \"pi_1577840204872417280\"\n    ]\n  }<\/code><\/pre>\n\n\n\n<p><strong>Crear un pago con documentos de conformidad<\/strong><\/p>\n\n\n\n<p>Si necesita enviarnos documentos de cumplimiento, hay tres pasos para crear un Pago con documentos de cumplimiento<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Cargue los documentos de conformidad mediante Crear un archivo<\/strong><\/li>\n<\/ol>\n\n\n\n<p><strong><em>Solicitar<\/em><\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>  curl --location --request POST 'https:\/\/apitest.wooshpay.com\/v1\/files' \\\n  --header 'Accept: application\/json' \\\n  --header 'Autorizaci\u00f3n: Su clave' \\\n  --header 'User-Agent: Apifox\/1.0.0' \\\n  --form 'file=@\"\/\u8def\u5f84\/xxx.pdf\"'<\/code><\/pre>\n\n\n\n<p><strong><em>Respuesta<\/em><\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>  {\n      \"id\": \"file_1654416327596572672\",\n      \"object\": \"archivo\",\n      \"creado\": 1683278565516,\n      \"url\": \"https:\/\/oss.swooshtransfer.cn\/oa\/product\/1654416327596572672_9gKPHbFsa5pUq47TafAMfVvJ.pdf\",\n      \"tipo\": \"pdf\",\n      \"filename\": \"1654416327596572672_9gKPHbFsa5pUq47TafAMfVvJ.pdf\"\n  }<\/code><\/pre>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\">\n<li><strong>Copie el<\/strong> <strong>URL<\/strong> <strong>en<\/strong> <strong>su respuesta<\/strong> En el caso anterior\uff0c el <code>URL<\/code> es <em><code>https:\/\/oss.swooshtransfer.cn\/oa\/product\/1654416327596572672_9gKPHbFsa5pUq47TafAMfVvJ.pdf<\/code><\/em><\/li>\n\n\n\n<li><strong>Solicitar<\/strong> <strong><code>metadatos<\/code><\/strong> <strong>al pago creado<\/strong><\/li>\n<\/ol>\n\n\n\n<ul class=\"wp-block-list\">\n<li><code>metadatos<\/code> : Consta de dos partes, la primera es el <code>clave<\/code> y la segunda parte es la <code>valor<\/code>.<\/li>\n\n\n\n<li>Ej: <code>\"metadatos\": {\"documento de cumplimiento\": \"url de su documento\", \"key2\": \"valor2\", \"...\": \"...\" }<\/code><\/li>\n<\/ul>\n\n\n\n<p><strong><em>Solicitar<\/em><\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>  {\n      {\n    \"beneficiario\": \"bf_1579357548861980672\",\n    \"metadatos\": {\n          \"documento de cumplimiento\": \"https:\/\/oss.swooshtransfer.cn\/oa\/product\/1654416327596572672_9gKPHbFsa5pUq47TafAMfVvJ.pdf\"\n      },\n\n    \"importe\": 666,\n    \"moneda\": \"cny\",\n    \"descripci\u00f3n\": \"Puedes a\u00f1adir la descripci\u00f3n aqu\u00ed\",\n    \"tipo\": \"cuenta_bancaria\",\n    \"datos_destino\": {\n      \"fuente\": {\n        \"nombre_titular_cuenta\": \"xxxx ltd\",\n        \"account_holder_type\": \"company\",\n        \"bank_name\": \"Bank of China\",\n        \"country\": \"CN\",\n        \"moneda\": \"CNY\",\n        \"n\u00famero_de_cuenta\": \"6210000000000002\"\n      }\n    },\n    \"payment_intents_id\": [\n      \"pi_1577840204872417280\"\n    ]\n  }\n  }<\/code><\/pre>\n\n\n\n<p><strong><em>Respuesta<\/em><\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>  {\n      \"id\": \"po_1654421512435793920\",\n      \"object\": \"pago\",\n      \"creado\": 1683279802000,\n      \"moneda\": \"CNY\",\n      \"importe\": 666,\n      \"descripci\u00f3n\": \"Puedes a\u00f1adir la descripci\u00f3n aqu\u00ed\",\n      \"metadatos\": {\n          \"documento de conformidad\": \"https:\/\/oss.swooshtransfer.cn\/oa\/product\/1654416327596572672_9gKPHbFsa5pUq47TafAMfVvJ.pdf\"\n      },\n      \"status\": \"pendiente\",\n      \"destino\": {\n          \"id\": \"ba_1654421514230956032\",\n          \"objeto\": \"cuenta_bancaria\",\n          \"creada\": 1683279801000,\n          \"pa\u00eds\": \"CN\",\n          \"moneda\": \"CNY\",\n          \"huella digital\": \"4732b34681776e6b2383da452cbbabbcd2228d48\",\n          \"last4\": \"0002\",\n          \"account_holder_name\": \"xxxx ltd\",\n          \"account_holder_type\": \"company\"\n      },\n      \"livemode\": falso,\n      \"type\": \"bank_account\",\n      \"method\": \"standard\",\n      \"beneficiario\": {\n          \"id\": \"bf_1654421512456765440\",\n          \"objeto\": \"beneficiario\",\n          \"tipo\": \"business\",\n          \"negocio\": {\n              \"direcci\u00f3n\": {\n                  \"ciudad\": \"Beijing\",\n                  \"country\": \"CN\",\n                  \"l\u00ednea1\": \"Bloque 3A\",\n                  \"l\u00ednea2\": \"Parque XX\",\n                  \"estado\": \"Beijing\",\n                  \"c\u00f3digo_postal\": \"323111\"\n              },\n              \"company_registered_name\": \"XXX ltd\",\n              \"additional_info\": {\n                  \"business_registration_number\": \"32342353535334234MCA4\",\n                  \"legal_rep_first_name\": \"Ming\",\n                  \"legal_rep_last_name\": \"Zhang\",\n                  \"legal_rep_id_type\": \"NATIONAL_ID\",\n                  \"legal_rep_id_number\": \"233923874838920238X\",\n                  \"legal_rep_email\": \"xxx@email.com\",\n                  \"legal_rep_phone\": \"13727282938\"\n              }\n          }\n      },\n      \"payment_intents_id\": [\n          \"pi_1577840204872417280\"\n      ]\n  }<\/code><\/pre>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-payout-failures\">Fallos en los pagos<\/h2>\n\n\n\n<p>Si la cuenta bancaria no puede recibir un pago por cualquier motivo, el banco nos devuelve los fondos. Este nos devuelve un error con el motivo del fallo. El banco puede tardar varios d\u00edas laborables en devolver el pago e informarnos de que ha fallado. Si esto ocurre, se le notificar\u00e1 en el Panel de control. Aseg\u00farate de que la informaci\u00f3n de la cuenta bancaria que facilitas es correcta. Si no lo es (un error tipogr\u00e1fico en el n\u00famero de cuenta, por ejemplo), es posible que los pagos se env\u00eden al titular de otra cuenta bancaria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-negative-payouts\">Pagos negativos<\/h2>\n\n\n\n<p>Cada pago refleja el saldo disponible de su cuenta en el momento en que se cre\u00f3. En algunos casos, puede tener un saldo de cuenta negativo. Por ejemplo, si recibes 100 USD en pagos pero devuelves 200 USD de pagos anteriores, el saldo de tu cuenta ser\u00eda de -100 USD. Si no recibes m\u00e1s pagos para equilibrar la cantidad negativa, fallar\u00e1 un nuevo pago.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-learn-about-the-outcomes-of-your-payout\">Conozca los resultados de su pago<\/h2>\n\n\n\n<p>Para saber si un pago a una cuenta bancaria se ha realizado correctamente, debe configurar un webhook.<\/p>\n\n\n\n<p>Los siguientes tipos de eventos son importantes cuando realiza pagos a cuentas bancarias, y puede crear webhooks para conocer el estado de su pago.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><code>pago.cancelado<\/code>: Se produce cada vez que se cancela un pago.<\/li>\n\n\n\n<li><code>pago.creado<\/code>: Se produce cada vez que se crea un pago.<\/li>\n\n\n\n<li><code>pago.fallido<\/code>: Se produce cuando falla un intento de pago.<\/li>\n\n\n\n<li><code>pago.pagado<\/code>: Se produce siempre que se espera que un pago est\u00e9 disponible en la cuenta de destino. Si el pago falla, tambi\u00e9n se env\u00eda una notificaci\u00f3n payout.failed, en un momento posterior.<\/li>\n\n\n\n<li><code>pago.actualizado<\/code>: Se produce cada vez que se actualiza un pago.<\/li>\n<\/ul>\n\n\n\n<p>Una vez identificados los eventos que desea supervisar, puede consultar la gu\u00eda de webhooks para <a href=\"\/es\/doc-2517709\/\">Crear un webhook<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-instant-payouts\">Pagos instant\u00e1neos<\/h2>\n\n\n\n<p>Con los Pagos Instant\u00e1neos, el env\u00edo de fondos a una cuenta bancaria admitida (en el Reino Unido) puede procesarse en un d\u00eda. Puede solicitar pagos instant\u00e1neos cualquier d\u00eda u hora, incluidos fines de semana y festivos, y los fondos suelen aparecer en la cuenta bancaria asociada.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th><strong>Pa\u00eds\/Regi\u00f3n<\/strong><\/th><th><strong>Velocidad de pago<\/strong><strong>(D\u00edas laborables)<\/strong><\/th><th><strong>Importe m\u00ednimo<\/strong><strong>(Moneda local)<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Reino Unido<\/td><td>0<\/td><td>0,01 EUR<\/td><\/tr><\/tbody><\/table><\/figure>","protected":false},"excerpt":{"rendered":"<p>Wooshpay es capaz de hacer pagos a su cuenta bancaria. Puede ver una lista de todos sus pagos en su cuenta bancaria en el panel de control. Tambi\u00e9n, puede recuperar la lista de pagos por API. Estado del pago Hay cinco estados de una solicitud de pago. Una vez creado el pago, el estado inicial ser\u00e1 [...]<\/p>","protected":false},"author":1,"featured_media":11958,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[316],"doc_tag":[327,324,323],"class_list":["post-11956","docs","type-docs","status-publish","has-post-thumbnail","hentry","doc_category-after-the-payments","doc_tag-global-payouts","doc_tag-open-api","doc_tag-payment"],"year_month":"2026-05","word_count":1750,"total_views":"2261","reactions":{"happy":"34","normal":"36","sad":"33"},"author_info":{"name":"wooshpaysite\u7ba1\u7406\u5458","author_nicename":"wooshpaysiteadmin","author_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/author\/wooshpaysiteadmin\/"},"doc_category_info":[{"term_name":"After the payments","term_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs-category\/after-the-payments\/"}],"doc_tag_info":[{"term_name":"global payouts","term_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs-tag\/global-payouts\/"},{"term_name":"open api","term_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs-tag\/open-api\/"},{"term_name":"payment","term_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs-tag\/payment\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.8 (Yoast SEO v24.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Payouts - WooshPay<\/title>\n<meta name=\"description\" content=\"Wooshpay is able to make payouts to your bank account. You can view a list of all of your payouts in your bank account on the Dashboard. Also, you can retrieve the payout list by API.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Payouts\" \/>\n<meta property=\"og:description\" content=\"Wooshpay is able to make payouts to your bank account. You can view a list of all of your payouts in your bank account on the Dashboard. Also, you can retrieve the payout list by API.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/\" \/>\n<meta property=\"og:site_name\" content=\"WooshPay\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-05T08:58:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png\" \/>\n\t<meta property=\"og:image:width\" content=\"751\" \/>\n\t<meta property=\"og:image:height\" content=\"317\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/\",\"url\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/\",\"name\":\"Payouts - WooshPay\",\"isPartOf\":{\"@id\":\"https:\/\/18.135.123.86\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png\",\"datePublished\":\"2023-08-05T08:58:26+00:00\",\"dateModified\":\"2023-08-05T08:58:27+00:00\",\"description\":\"Wooshpay is able to make payouts to your bank account. You can view a list of all of your payouts in your bank account on the Dashboard. Also, you can retrieve the payout list by API.\",\"breadcrumb\":{\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/#primaryimage\",\"url\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png\",\"contentUrl\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png\",\"width\":751,\"height\":317,\"caption\":\"payout status\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/18.135.123.86\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/www.wooshpay.com\/it\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Payouts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/18.135.123.86\/es\/#website\",\"url\":\"https:\/\/18.135.123.86\/es\/\",\"name\":\"WooshPay\",\"description\":\"One-stop payment platform\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/18.135.123.86\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Payouts - WooshPay","description":"Wooshpay es capaz de hacer pagos a su cuenta bancaria. Puede ver una lista de todos sus pagos en su cuenta bancaria en el panel de control. Tambi\u00e9n, puede recuperar la lista de pagos por API.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/","og_locale":"es_ES","og_type":"article","og_title":"Payouts","og_description":"Wooshpay is able to make payouts to your bank account. You can view a list of all of your payouts in your bank account on the Dashboard. Also, you can retrieve the payout list by API.","og_url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/","og_site_name":"WooshPay","article_modified_time":"2023-08-05T08:58:27+00:00","og_image":[{"width":751,"height":317,"url":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/","url":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/","name":"Payouts - WooshPay","isPartOf":{"@id":"https:\/\/18.135.123.86\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/#primaryimage"},"image":{"@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/#primaryimage"},"thumbnailUrl":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png","datePublished":"2023-08-05T08:58:26+00:00","dateModified":"2023-08-05T08:58:27+00:00","description":"Wooshpay es capaz de hacer pagos a su cuenta bancaria. Puede ver una lista de todos sus pagos en su cuenta bancaria en el panel de control. Tambi\u00e9n, puede recuperar la lista de pagos por API.","breadcrumb":{"@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/#primaryimage","url":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png","contentUrl":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png","width":751,"height":317,"caption":"payout status"},{"@type":"BreadcrumbList","@id":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/docs\/payouts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/18.135.123.86\/es\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/www.wooshpay.com\/it\/docs\/"},{"@type":"ListItem","position":3,"name":"Payouts"}]},{"@type":"WebSite","@id":"https:\/\/18.135.123.86\/es\/#website","url":"https:\/\/18.135.123.86\/es\/","name":"WooshPay","description":"Plataforma de pago \u00fanica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/18.135.123.86\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"uagb_featured_image_src":{"full":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png",751,317,false],"thumbnail":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status-150x150.png",150,150,true],"medium":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status-300x127.png",300,127,true],"medium_large":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png",751,317,false],"large":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png",751,317,false],"1536x1536":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png",751,317,false],"2048x2048":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status.png",751,317,false],"trp-custom-language-flag":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/08\/payout-status-18x8.png",18,8,true]},"uagb_author_info":{"display_name":"wooshpaysite\u7ba1\u7406\u5458","author_link":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/author\/wooshpaysiteadmin\/"},"uagb_comment_info":0,"uagb_excerpt":"Wooshpay is able to make payouts to your bank account. You can view a list of all of your payouts in your bank account on the Dashboard. Also, you can retrieve the payout list by API. Payout Status There are five states of one payout request. Once the payout is created, the initial state will&hellip;","_links":{"self":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/docs\/11956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/comments?post=11956"}],"version-history":[{"count":0,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/docs\/11956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/media\/11958"}],"wp:attachment":[{"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/media?parent=11956"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/doc_category?post=11956"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/d2jcf4noflr1cd.cloudfront.net\/es\/wp-json\/wp\/v2\/doc_tag?post=11956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}